{"id":7453,"date":"2018-04-18T06:11:30","date_gmt":"2018-04-18T04:11:30","guid":{"rendered":"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=7453"},"modified":"2019-03-11T11:34:16","modified_gmt":"2019-03-11T10:34:16","slug":"triteam-siegerland-nimmt-erfolgreich-an-der-sichtungsveranstaltung-des-nrw-triathlonverbandes-teil","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/7453\/","title":{"rendered":"TriTeam Siegerland nimmt erfolgreich an der Sichtungsveranstaltung des NRW-Triathlonverbandes teil"},"content":{"rendered":"<p><em><strong>Kreuztal, 17. April 2018 &#8211;<\/strong> <\/em>Sieben junge Athleten des TriTeams Siegerland fuhren zusammen mit ihrem Trainerteam am letzten Samstag nach Werne zur zentralen Sichtungsveranstaltung des NRW-Triathlonverbandes.<\/p>\n<p><!--more--><\/p>\n<p>Motiviert und frisch aus dem Trainingslager galt es f\u00fcr die Athleten im Alter von 10 bis 12 Jahre ihre F\u00e4higkeiten im Laufen, Schwimmen, in der Athletik sowie auf einem Radparkour unter Beweis zu stellen. Und die Ergebnisse k\u00f6nnen sich sehen lassen: f\u00fcnf der TriTeam-Starter erf\u00fcllten die geforderten Normen und wurden in das Programm \u201eTalentsichtung \/ Talentf\u00f6rderung\u201c des NRWTVs aufgenommen. Auch die beiden anderen Teilnehmer freuten sich \u00fcber neue pers\u00f6nliche Bestleistungen.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 align=\"center\"><strong><em>Text: TriTeam Siegerland<\/em><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kreuztal, 17. April 2018 &#8211; Sieben junge Athleten des TriTeams Siegerland fuhren zusammen mit ihrem Trainerteam am letzten Samstag nach Werne zur zentralen Sichtungsveranstaltung des NRW-Triathlonverbandes.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/7453\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[65,236,307,308,309,310],"class_list":["post-7453","post","type-post","status-publish","format-standard","hentry","category-triathlon","tag-65","tag-triteam-siegerland","tag-traithlon","tag-sichtung","tag-nrw","tag-werne","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/7453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=7453"}],"version-history":[{"count":2,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/7453\/revisions"}],"predecessor-version":[{"id":9427,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/7453\/revisions\/9427"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=7453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=7453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=7453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}