{"id":6934,"date":"2015-11-11T15:21:07","date_gmt":"2015-11-11T14:21:07","guid":{"rendered":"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=6934"},"modified":"2019-04-15T12:12:38","modified_gmt":"2019-04-15T10:12:38","slug":"absage-1-huestener-crossrennen-21-11-2015","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/6934\/","title":{"rendered":"ABSAGE  1. H\u00fcstener Crossrennen 21.11.2015"},"content":{"rendered":"<p>Leider m\u00fcssen wir unser 1. H\u00fcstener Crossrennen am 21.11.2015 absagen.<\/p>\n<p><!--more--><\/p>\n<p>Grund hierf\u00fcr ist der bisherige, geringe Meldeeingang, bis 11.11.2015 liegen nur 34 Meldungen in den ausgeschriebenen Klassen vor.<br \/>\nSomit ist aus sportlicher, wirtschaftlicher Sicht sowie der Gesamtaufwand f\u00fcr die Veranstaltung nicht zu vertreten.<\/p>\n<p>Wir bitten um Euer Verst\u00e4ndnis, in der Saison 2016\/17 versuchen wir einen erneuten Anlauf.<\/p>\n<p>&nbsp;<\/p>\n<p>Mit sportlichen Gr\u00fc\u00dfen<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Bernd Brodowski<\/strong><br \/>\n<em>Gesch\u00e4ftsf\u00fchrer d. RC Victoria Neheim e.V.<\/em><br \/>\n&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leider m\u00fcssen wir unser 1. H\u00fcstener Crossrennen am 21.11.2015 absagen.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/6934\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[151,166,197,342],"class_list":["post-6934","post","type-post","status-publish","format-standard","hentry","category-cross-querfeldeinrennen","tag-151","tag-absage","tag-cross","tag-rc-victoria-neheim","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/6934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=6934"}],"version-history":[{"count":3,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/6934\/revisions"}],"predecessor-version":[{"id":10634,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/6934\/revisions\/10634"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=6934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=6934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=6934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}