{"id":5933,"date":"2012-07-02T08:54:04","date_gmt":"2012-07-02T06:54:04","guid":{"rendered":"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=5933"},"modified":"2019-04-15T10:49:48","modified_gmt":"2019-04-15T08:49:48","slug":"hagener-urlaubskorb-2012","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/5933\/","title":{"rendered":"Hagener Urlaubskorb 2012"},"content":{"rendered":"<p>\u201eWann wird\u2019s mal wieder richtig Sommer?\u201c fragte einst Rudi Carrell und spricht damit noch heute vielen Hagenern und Deutschen aus der Seele.<br \/>\n<!--more--><br \/>\n\u201eEin Sommer wie er fr\u00fcher einmal war\u201c, wer stellt sich diese Frage nicht jedes Jahr wieder? \u201eMit Sonnenschein von Juni bis September\u201c, dar\u00fcber w\u00fcrden sich wohl viele Freizeitsportler, die ihren Sport gerne an der frischen Lust aus\u00fcben, freuen. \u201eUnd nicht so nass und so sibirisch wie im letzten Jahr\u201c, das hoffen insbesondere die Radwanderer des Rad-Sport-Club Hagen, die vor allem im vergangenen Jahr auf ihrer 9-t\u00e4gigen Radtour zum Bundes-Radsport-Treffen ziemlich nass geworden sind.<\/p>\n<p>Aber sonniges, warmes und trockenes Wetter erhoffen sich die Organisatoren des RSC auch f\u00fcr die Radtouren, die diesen Sommer wieder im Rahmen des Hagener Urlaubskorbes angeboten werden. In diesem Jahr stehen insgesamt 10 gef\u00fchrte Radtouren auf dem Programm. \u201eWir brauchten fr\u00fcher keine gro\u00dfe Reise\u201c, das dies heute noch gilt, will der RSC mit seinem Angebot auch dieses Jahr wieder interessierten Hagener B\u00fcrgerinnen und B\u00fcrgern zeigen. Die Ziele sind abwechslungsreich, die Strecken f\u00fchren immer abseits des Verkehrs durch die Natur der Hagener Umgebung. Sie sollen den Daheimgebliebenen ein wenig Urlaubsflair sowie einen sch\u00f6nen Tag in Gesellschaft Gleichgesinnter bieten.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5929\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern4.jpg\" alt=\"radwandern4\" width=\"375\" height=\"500\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern4.jpg 640w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern4-225x300.jpg 225w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5930\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern1.jpg\" alt=\"radwandern1\" width=\"500\" height=\"343\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern1.jpg 640w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern1-300x206.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Los geht es am kommenden Sonntag <b>8. Juli<\/b> mit einer 70 Km langen Tour entlang der Fl\u00fcsse Ruhr, H\u00f6nne und Lenne sowie einer ehemaligen Bahntrasse in den M\u00e4rkischen Kreis. Die Tour ist aufgrund ihrer L\u00e4nge f\u00fcr Untrainierte nur bedingt geeignet, jedoch \u00fcberwiegend flach. Treffpunkt ist um 10:30 Uhr an der Lennebr\u00fccke in Halden (Ecke Buschm\u00fchlen-\/Industriestr.).<\/p>\n<p>Am Sonntag <b>15. Juli<\/b> wird durch Wiesen und W\u00e4lder \u00fcber den Rheinischen Esel zur Ruhr geradelt. Es wird zu Kaffee und Kuchen eingekehrt. F\u00fcr die 55 Km ist ein wenig Kondition erforderlich. Treffpunkt ist um 11:00 Uhr ebenfalls an der Lennebr\u00fccke.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5931\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern2.jpg\" alt=\"radwandern2\" width=\"458\" height=\"500\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern2.jpg 640w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern2-275x300.jpg 275w\" sizes=\"auto, (max-width: 458px) 100vw, 458px\" \/><\/p>\n<p>Die in der Vergangenheit \u00e4u\u00dferst beliebte und vielleicht reizvollste Tour des diesj\u00e4hrigen Angebots \u00fcber die ehemalige Stra\u00dfenbahntrasse der Linie 11 wird am Sonntag <b>22. Juli<\/b> angeboten. Die Tour durch herrliche Landschaft mit tollen Ausblicken und durch die Ennepeauen startet um 11:00 Uhr an der Volmegalerie. Es ist ein wenig Kondition erforderlich.<\/p>\n<p>Danach nimmt sich der RSC eine kleine Auszeit und startet zu seinem Saisonh\u00f6hepunkt \u2013 dem Bundes-Rad-Sport-Treffen, das in diesem Jahr in Ulm und Neu-Ulm stattfindet. An 8 Tagen wird mit 23 Teilnehmern entlang der Donau, der Altm\u00fchl sowie des Rhein-Main-Donau-Kanals geradelt.<\/p>\n<p>Am Sonntag <b>12. August<\/b> wird dann wieder eine abwechslungsreiche Tour entlang der Ruhr, des Baarbachs sowie einer ehemaligen Bahntrasse im Urlaubskorb angeboten. Die 55 Km lange Tour ist bedingt f\u00fcr Untrainierte geeignet und beginnt um 11:00 Uhr an der Lennebr\u00fccke in Halden.<\/p>\n<p>Den Abschluss des diesj\u00e4hrigen Angebots bildet die Tour am Samstag <b>18. August<\/b>. Durch abwechslungsreiche Landschaft, teilweise \u00fcber den Ruhrtalradweg sowie entlang des \u00d6lbachs wird zum \u00dcmminger See geradelt. In die Startzeiten im Urlaubskorb hat sich leider ein kleiner Fehler eingeschlichen. Treffpunkte sind um 10:00 Uhr (nicht um 11:00) an der Lennebr\u00fccke in Halden (ca. 70 Km) sowie um 11:00 Uhr (nicht um 12:00) am Schiffsanleger in Wetter (ca. 50 Km). F\u00fcr die 70-Km-Tour sind 2 Pausen eingeplant. Die kurze Tour ist f\u00fcr Untrainierte geeignet, f\u00fcr die lange sollte ein wenig Kondition vorhanden sein.<\/p>\n<p>Neben dem Angebot am Wochenende bietet der RSC Hagen in diesem Jahr auch gef\u00fchrte Tagestouren am <b>Mittwoch<\/b> an. Die ca. 50 \u2013 70 Km langen Touren finden nur bei trockener Witterung statt. Treffpunkt ist an folgenden Mittwochen jeweils um 10:30 Uhr an der Lennebr\u00fccke in Halden: 11. Juli, 18. Juli, 25. Juli, 8. August und 15. August.<\/p>\n<p>Bei allen angebotenen Radtouren wird immer mindestens eine l\u00e4ngere Pause mit Einkehr gemacht. Es sind ein verkehrssicheres Fahrrad sowie Verpflegung mitzubringen. Die Geschwindigkeit richtet sich immer nach dem Langsamsten in der Gruppe. Es wird darauf geachtet, dass jeder Teilnehmer gut mithalten kann. Bei schlechter Witterung sind Strecken\u00e4nderungen vorbehalten.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5932\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern3.jpg\" alt=\"radwandern3\" width=\"481\" height=\"500\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern3.jpg 640w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2012\/07\/radwandern3-289x300.jpg 289w\" sizes=\"auto, (max-width: 481px) 100vw, 481px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Wer sich gerne noch ein wenig fit radeln m\u00f6chte, kann dies im Rahmen des Anti-Stress-Bikings mittwochs um 18 Uhr und freitags um 17 Uhr ab der Lennebr\u00fccke in Halden (ca. 25-40 Km). Informationen zu den Fahrten im Urlaubskorb sowie dem Angebot des RSC Hagen gibt es im Internet unter <i><a href=\"http:\/\/www.rsc-hagen.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.rsc-hagen.de<\/a><\/i> sowie bei Karl-Heinz und Marlies Kubas (Tel.: 02331 50586). \u201eWann wird\u2019s mal wieder richtig Sommer?\u201c<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eWann wird\u2019s mal wieder richtig Sommer?\u201c fragte einst Rudi Carrell und spricht damit noch heute vielen Hagenern und Deutschen aus der Seele.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/5933\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[116,414,532],"class_list":["post-5933","post","type-post","status-publish","format-standard","hentry","category-radwandern","tag-116","tag-radwandern","tag-rsc-hagen","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/5933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=5933"}],"version-history":[{"count":3,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/5933\/revisions"}],"predecessor-version":[{"id":10593,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/5933\/revisions\/10593"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=5933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=5933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=5933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}