{"id":5221,"date":"2010-11-12T08:56:54","date_gmt":"2010-11-12T07:56:54","guid":{"rendered":"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=5221"},"modified":"2019-03-05T10:52:56","modified_gmt":"2019-03-05T09:52:56","slug":"online-anmeldung","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/5221\/","title":{"rendered":"Westfalen Winter Bike Trophy 2011-Online-Anmeldung freigeschaltet"},"content":{"rendered":"<p>Von heute an ist die Online-Anmeldung zur Westfalen Winter Bike Trophy 2011 auf der Internetseite der <a href=\"http:\/\/www.westfalen-winter-bike-trophy.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Westfalen Winter Bike Trophy<\/a> und des Radsportbezirks Westfalen Mitte freigeschaltet.<!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-5220\" style=\"display: block; margin-left: auto; margin-right: auto;\" src=\"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/11\/PlakatWWBT2011.jpg\" alt=\"PlakatWWBT2011\" width=\"360\" height=\"508\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/11\/PlakatWWBT2011.jpg 490w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/11\/PlakatWWBT2011-212x300.jpg 212w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><\/p>\n<p>Die Veranstaltergemeinschaft hofft, dass sich dadurch die interessierten Mountainbiker und Freizeitfahrer schon vor dem ersten Lauf am 9. Januar 2011, der bei den Radsportlern des SC Capelle stattfindet, anmelden. Vorteil der Online-Anmeldung ist, dass beim ersten und allen darauf folgenden L\u00e4ufen die registrierten Teilnehmer nur noch ihren Namen nennen m\u00fcssen, um seine Startkarte der Tagesveranstaltung zu bekommen. In Capelle und den weiteren L\u00e4ufen der WWBT steht f\u00fcr die online angemeldeten Sportler ein Servicepaket mit Lenkernummer, WWBT-Serienkarte und weiteren Informationen bereit.<\/p>\n<p>&nbsp;<\/p>\n<p><i>Norbert Schnitzmeier<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von heute an ist die Online-Anmeldung zur Westfalen Winter Bike Trophy 2011 auf der Internetseite der Westfalen Winter Bike Trophy und des Radsportbezirks Westfalen Mitte freigeschaltet.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/5221\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[75,76,98,100],"class_list":["post-5221","post","type-post","status-publish","format-standard","hentry","category-wwbt-rtfctf","tag-westfalen-winter-bike-trophy","tag-wwbt","tag-98","tag-online-anmeldung","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/5221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=5221"}],"version-history":[{"count":3,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/5221\/revisions"}],"predecessor-version":[{"id":9069,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/5221\/revisions\/9069"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=5221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=5221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=5221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}