{"id":5016,"date":"2010-05-17T08:55:48","date_gmt":"2010-05-17T06:55:48","guid":{"rendered":"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=5016"},"modified":"2019-05-13T11:23:50","modified_gmt":"2019-05-13T09:23:50","slug":"bezirksfahrer-bei-der-tmp-tour","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/5016\/","title":{"rendered":"Bezirksfahrer bei der TMP-Tour"},"content":{"rendered":"<p>Am letzten Wochenende starteten Jan Tschernoster (Werne) und Timo Goeke (Unna) bei der TMP-Tour f\u00fcr die U15-Auswahlmannschaft des Landesverbandes.<br \/>\n<!--more--><\/p>\n<p>Beim Prolog auf dem Firmengel\u00e4nde des Namensgebers der Tour zeigte sich Jan Tschernoster immer wieder in den vorderen Reihen.<br \/>\nAm n\u00e4chsten Morgen war um 7:50h die Abfahrt zum Zeitfahren geplant. Das Auto sprang jedoch nicht an. So musste eine andere, 30km entfernt stationierte Mannschaft, die vier Fahrer abholen und zum Start bringen. Tschernoster, der als erstes starten sollte, hatte durch die Versp\u00e4tung nur noch 20min bis zum Start. Der Unneraner Timo Goeke konnte sich hingegen noch warmfahren und erreichte eine passable Zeit.<\/p>\n<p>Bei dem Stra\u00dfenrennen am selben Tag, der schwersten Etappe, musste Tschernoster auf der Windkante nach dem zweiten Berg etwas Zeit einb\u00fc\u00dfen. Timo Goeke musste auch kurzzeitig nach einer Attacke abrei\u00dfen lassen, kam jedoch wieder in die Spitzengruppe zur\u00fcck und konnte sich so in einem Kraftakt unter die TOP 15 der Gesamtwertung schieben.<\/p>\n<p>Die Abschlussetappe wurde in sch\u00f6ner Kulisse in der Altstadt von Bad Langensalza ausgetragen. Hier galt es auf langen Kopfsteinpflasterpassagen in einem schnellen Rennen vor allem Fahrtechnik zu beweisen. Jan Tschernoster kam mit diesem Terrain \u00fcberraschend gut zurecht und konnte sich einige Male vorne pr\u00e4sentieren. Timo Goeke kam ebenfalls mit dem Hauptfeld ins Ziel und sicherte sich so Platz 12 in der Gesamtwertung.<\/p>\n<p><em>Der Marder, der den Motorschaden vor dem Zeitfahren verursacht hatte, wurde \u00fcbrigens nicht gefunden.<\/em><\/p>\n<p>In der Klasse U17 war Lars Volmerg aus Werne f\u00fcr den Landesverband am Start. Er konnte jedoch als Fahrer des j\u00fcngeren Jahrgangs keine entscheidenden Akzente setzen.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5013\" src=\"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/05\/tmp_mannschaft640.jpg\" alt=\"tmp_mannschaft640\" width=\"500\" height=\"398\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/05\/tmp_mannschaft640.jpg 640w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/05\/tmp_mannschaft640-300x239.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5014\" src=\"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/05\/tmp_goeke_schlussetappe640.jpg\" alt=\"tmp_goeke_schlussetappe640\" width=\"500\" height=\"371\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/05\/tmp_goeke_schlussetappe640.jpg 640w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/05\/tmp_goeke_schlussetappe640-300x223.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5015\" src=\"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/05\/tmp_tschernoster_640.jpg\" alt=\"tmp_tschernoster_640\" width=\"466\" height=\"500\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/05\/tmp_tschernoster_640.jpg 640w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2010\/05\/tmp_tschernoster_640-280x300.jpg 280w\" sizes=\"auto, (max-width: 466px) 100vw, 466px\" \/><br \/>\n&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am letzten Wochenende starteten Jan Tschernoster (Werne) und Timo Goeke (Unna) bei der TMP-Tour f\u00fcr die U15-Auswahlmannschaft des Landesverbandes.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/5016\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[768,1045,1046,71,86,88,218,557],"class_list":["post-5016","post","type-post","status-publish","format-standard","hentry","category-strassenrennsport","tag-timo-goeke","tag-tmp-tour","tag-lars-volmerg","tag-rsv-unna","tag-86","tag-rsc-werne","tag-strasse","tag-jan-tschernoster","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/5016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=5016"}],"version-history":[{"count":3,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/5016\/revisions"}],"predecessor-version":[{"id":12292,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/5016\/revisions\/12292"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=5016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=5016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=5016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}