{"id":4796,"date":"2009-12-10T08:58:41","date_gmt":"2009-12-10T07:58:41","guid":{"rendered":"http:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=4796"},"modified":"2019-06-09T12:03:32","modified_gmt":"2019-06-09T10:03:32","slug":"spannung-vor-der-rtf-bezirksehrung","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/4796\/","title":{"rendered":"Spannung vor der RTF Bezirksehrung"},"content":{"rendered":"<p>Gut eine Woche vor der RTF\/CTF Ehrung steigt die Spannung bei vielen Sportlerinnen, Sportler und Vereine im Radsportbezirk Westfalen Mitte. An 70 Vereine des BZ gingen in der vergangenen Woche die Einladung raus. <!--more-->Dabei auch die Pers\u00f6nliche Einladung f\u00fcr 24 Tourenfahrer in den vier Einzelklassen. Zw\u00f6lf Sch\u00fcler und Jugendlichen werden zudem f\u00fcr ihr RTF Jahr geehrt.. Dazu kommen noch die 28 Vereinsmannschaften bei den Frauen, M\u00e4nner, Sch\u00fclern und Jugendlichen.<\/p>\n<p>Titelverteidiger bei den Herren- und Damenmannschaften ist das Radteam Hamm, die in ihrem Jubil\u00e4umsjahr es noch mal wissen wollen. Bei den Jugendmannschaften hofft der RSV Dortmund Nord auf eine Titelverteidigung.<\/p>\n<p>Auch bei den TOP 100 werden in diesem Jahr die besten drei Frauen und M\u00e4nner der vergangenen 12 Jahre ausgezeichnet. Doris B\u00f6hmeke und Gerd Glowacki von der RSG Herne waren die ersten beiden Preistr\u00e4ger.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Veranstaltung findet am 20. Dezember 2009 wie in den vergangenen Jahren in der Europaschule Dortmund, Am Gottesacker in 44141 Dortmund statt. Einlass in die Mensa der Schule ist um 9.30 Uhr, Beginn der Ehrung 10.00 Uhr.<\/p>\n<p>Neben den Pokalen f\u00fcr die Sportler stehen f\u00fcr die Vereine die BDR Jahresauszeichnung und die bestellten NRW Info Hefte bereit.<\/p>\n<p>Zum Ende der Veranstaltung gibt es schon Traditionell eine Gulaschsuppe.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Norbert Schnitzmeier<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gut eine Woche vor der RTF\/CTF Ehrung steigt die Spannung bei vielen Sportlerinnen, Sportler und Vereine im Radsportbezirk Westfalen Mitte. An 70 Vereine des BZ gingen in der vergangenen Woche die Einladung raus. <\/p><p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/4796\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[58,66,77,365,675],"class_list":["post-4796","post","type-post","status-publish","format-standard","hentry","category-bezirk","tag-bezirk","tag-bdr","tag-77","tag-ehrung","tag-jahresauszeichnung","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/4796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=4796"}],"version-history":[{"count":3,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/4796\/revisions"}],"predecessor-version":[{"id":13608,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/4796\/revisions\/13608"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=4796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=4796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=4796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}