{"id":17981,"date":"2026-07-14T09:29:00","date_gmt":"2026-07-14T07:29:00","guid":{"rendered":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=17981"},"modified":"2026-07-14T09:29:00","modified_gmt":"2026-07-14T07:29:00","slug":"rembe-rad-net-bestimmt-renngeschehen-der-tour-of-austria-mit-frauen-starten-in-belgien","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/17981\/","title":{"rendered":"REMBE | rad-net bestimmt Renngeschehen der Tour of Austria mit &#8211; Frauen starten in Belgien"},"content":{"rendered":"<p>Das Team <em>REMBE | rad-net<\/em> hat bei der Tour of Austria (UCI 2.1) einige gute Ergebnisse eingefahren und die Etappen mitbestimmt. Mauro Brenner wurde zudem zum aktivsten Fahrer der Rundfahrt ausgezeichnet.<!--more--><\/p>\n<p>Auf vier der f\u00fcnf Etappen war Brenner als Ausrei\u00dfer unterwegs. Die Gruppen holten jeweils mehrere Minuten Vorsprung heraus, wurden aber vom Feld, in dem WorldTour-Mannschaften wie UAE-Team Emirates-XRG, Netcompany-Ineos und Lidl-Trek vertreten waren, stets vor dem Ziel gestellt. F\u00fcr das beste Tagesergebnis sorgte Jermaine Zemke. Der 20-J\u00e4hrige spurtete auf dem vierten Teilst\u00fcck aus einer rund zehnk\u00f6pfigen Gruppe auf den f\u00fcnften Platz. Auch auf der Schlussetappe erzielte er als Zehnter ein weiteres gutes Resultat. In der Gesamtwertung belegte Johannes Adamietz beim Gesamtsieg von Gregor M\u00fchlberger (Decathlon-CMA CGM) den 21. Platz und war damit bester Deutscher.<\/p>\n<p>Ab Mittwoch ist das Team <em>REMBE | rad-net women<\/em> ebenfalls wieder international unterwegs, denn es startet bei der Baloise Ladies Tour (UCI 2.1) in Belgien. Auch die Frauen treffen dort auf starke Teams wie Canyon-Sram, Lidl-Trek, Visma-Lease a Bike und SD Worx-Protime um Superstar Lotte Kopecky. \u00abTrotzdem wollen wir uns nicht verstecken und die Etappen mitbestimmen\u00bb, so Andr\u00e9 Korff, Sportlicher Leiter des Teams <em>REMBE | rad-net<\/em>.<\/p>\n<hr \/>\n<p><span style=\"color: #339966;\"><em><strong>Das Team <\/strong><\/em><strong>REMBE | rad-net<\/strong><strong> women<\/strong><em><strong> bei der Baloise Ladies Tour (UCI 2.1):<\/strong><\/em><\/span><br \/>\nIana Baltes, Franziska Brau\u00dfe, Miriam Gerwig, Hannah Kunz, Aileen Schweikart<br \/>\n<strong><em>Sportliche Leitung:<\/em><\/strong> Ralf Grabsch, Andr\u00e9 Korff<\/p>\n<hr \/>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2026\/07\/austria26-brenner.jpg\" alt=\"Mauro Brenner war bei der Tour of Austria viermal als Ausrei\u00dfer unterwegs. (Foto: Mario Stiehl)\" width=\"500\" height=\"333\" \/><br \/>\n<i> Mauro Brenner war bei der Tour of Austria viermal als Ausrei\u00dfer unterwegs.<br \/>\n(Foto: Mario Stiehl)<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Team REMBE | rad-net hat bei der Tour of Austria (UCI 2.1) einige gute Ergebnisse eingefahren und die Etappen mitbestimmt. Mauro Brenner wurde zudem zum aktivsten Fahrer der Rundfahrt ausgezeichnet.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/17981\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[1732,1745,1777,1779,218,1258,1566,1579,1593,1691,1703,1704,1708,1710],"class_list":["post-17981","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-aileen-schweikart","tag-miriam-gerwig","tag-tour-of-austria","tag-baloise-ladies-tour","tag-strasse","tag-johannes-adamietz","tag-1566","tag-rembe-rad-net","tag-jermaine-zemke","tag-mauro-brenner","tag-rembe-rad-net-women","tag-hannah-kunz","tag-iana-baltes","tag-franziska-brausse","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/17981","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=17981"}],"version-history":[{"count":1,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/17981\/revisions"}],"predecessor-version":[{"id":17983,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/17981\/revisions\/17983"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=17981"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=17981"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=17981"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}