{"id":16766,"date":"2022-01-07T10:22:56","date_gmt":"2022-01-07T09:22:56","guid":{"rendered":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=16766"},"modified":"2022-01-07T10:25:08","modified_gmt":"2022-01-07T09:25:08","slug":"saris-rouvy-sauerland-team-verpflichtet-bahnsprinter-max-briese","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/16766\/","title":{"rendered":"SARIS ROUVY Sauerland Team verpflichtet Bahnsprinter Max Briese"},"content":{"rendered":"<p><em>Eslohe, den 6.1.22<\/em><\/p>\n<p><strong>Vizeweltmeister im Bahnsprint wechselt auf die Stra\u00dfe<\/strong><\/p>\n<p>Max Briese startete bisher als Bahnsprinter und ist heute eine der Nachwuchshoffnungen im SARIS ROUVY Sauerland Team. W\u00e4hrend er als Sprinter bereits Medaillen bei Nationalen und internationalen Meisterschaften sammeln konnte, beschr\u00e4nkt sich seine Stra\u00dfenerfahrung auf einige wenige Rennen in den unteren Nachwuchsklassen. Zu seinen gr\u00f6\u00dften Erfolgen z\u00e4hlten vergangenes Jahr die Silbermedaille im Team Sprint bei der Junioren WM in Kairo und der Deutsche Meister Titel im Sprint bei der DM in K\u00f6ln.<!--more--><\/p>\n<p>Der 18 j\u00e4hrige Bahn- Nationalfahrer kommt vom PSV Rostock zum SARIS ROUVY Sauerland Team. Nach ersten Gespr\u00e4chen im November wollte man Briese zuerst im Trainingslager im Januar testen und sich gegenseitig beschnuppern. \u201eMax ist zum ersten Team-Treffen im Dezember gekommen und ist mit einigen Sauerl\u00e4ndern direkt die vier Winterbahnrennen in B\u00fcttgen gefahren. Er passte menschlich gut rein und hat mit einem starken 3. Platz in der Gesamtwertung \u00fcberzeugt. Der Youngster konnte in den Ausdauerdisziplinen mithalten und hat auch den ein oder anderen Lauf gewonnen\u201c, erkl\u00e4rt der Olympia St\u00fctzpunkt Trainer Wolfgang Oschwald.<\/p>\n<p>Der Sauerl\u00e4nder Plan ist nun den jungen Sportler behutsam aufzubauen und seine ersten Rennen im M\u00e4rz fahren zu lassen. Max Briese wird mit einem Teil des Teams sein Debut bei der Istrien Spring Trophy feiern. Im Detail sind das eine mehrt\u00e4gige Rundfahrt und zwei Eintagesrennen im Norden Kroatiens. Schafft der Rostocker tats\u00e4chlich einen guten Wechsel in die Stra\u00dfenszene, kann er im Sauerland Team die L\u00fccke des fehlenden Sprinters f\u00fcllen. \u201eLeider hat uns Lars Kulbe in Richtung Studium in Freiburg verlassen. Er war ein Riesentalent und fehlt uns im Finale der Rennen. Der Kontakt zu Max Briese war jetzt ein Gl\u00fccksfall, auch wenn wir wissen, dass es seine Zeit braucht\u201c, so Wofgang Oschwald abschliessend.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2022\/01\/IMG_0546-min-scaled.jpg\" alt=\"Siegerehrung der Winterbahn in B\u00fcttgen\" width=\"375\" height=\"500\" \/><br \/>\n<em>Quelle Sauerland Team<\/em><br \/>\n<em>Siegerehrung der Winterbahn in B\u00fcttgen<\/em><br \/>\n<em>(Michel Giesselmann, Tim Teutenberg, Max David Briese vlnr)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>kind regards \/ C \u043d\u0430\u0438\u043b\u0443\u0447\u0448\u0438\u043c\u0438 \u043f\u043e\u0436\u0435\u043b\u0430\u043d\u0438\u044f\u043c\u0438!\/ mit sportlichen Gr\u00fc\u00dfen \/ met vriendelijke groet<\/p>\n<p><b>J\u00f6rg Scherf<\/b><br \/>\n<i>gesch\u00e4ftsf\u00fchrender Gesellschafter\/ CEO<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eslohe, den 6.1.22<\/p>\n<p>Vizeweltmeister im Bahnsprint wechselt auf die Stra\u00dfe<\/p>\n<p>Max Briese startete bisher als Bahnsprinter und ist heute eine der Nachwuchshoffnungen im SARIS ROUVY Sauerland Team. W\u00e4hrend er als Sprinter bereits Medaillen bei Nationalen und internationalen Meisterschaften sammeln konnte, beschr\u00e4nkt sich seine Stra\u00dfenerfahrung auf einige wenige Rennen in den unteren Nachwuchsklassen. Zu seinen gr\u00f6\u00dften &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/16766\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,28,33],"tags":[218,266,1349,1386,1387],"class_list":["post-16766","post","type-post","status-publish","format-standard","hentry","category-bahnrennsport","category-strassenrennsport","category-rennsport","tag-strasse","tag-bahn","tag-1349","tag-saris-rouvy-sauerland-team","tag-max-briese","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/16766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=16766"}],"version-history":[{"count":4,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/16766\/revisions"}],"predecessor-version":[{"id":16771,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/16766\/revisions\/16771"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=16766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=16766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=16766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}