{"id":16317,"date":"2020-08-27T08:50:49","date_gmt":"2020-08-27T06:50:49","guid":{"rendered":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=16317"},"modified":"2020-08-27T08:51:26","modified_gmt":"2020-08-27T06:51:26","slug":"strassen-dm-am-sachsenring-joann-leinau-ueberzeugt-spitzenplatzierung-bei-internationalen-rennen-in-den-letzten-tagen","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/16317\/","title":{"rendered":"Stra\u00dfen DM am Sachsenring- Joann Leinau \u00fcberzeugt, Spitzenplatzierung bei internationalen Rennen in den letzten Tagen"},"content":{"rendered":"<p><i>Eslohe, den 26.8.2020<\/i><\/p>\n<p><b>Deutsche Profimeisterschaft am Sachsenring<\/b><\/p>\n<p>Beim Aussenseitersieg des Cross-Spezialisten Marcel Meisen \u00fcberzeugte aus Sauerl\u00e4nder Sicht der H\u00fcstener Joann Leinau. Mit seinem Angriff \u00fcber knapp die H\u00e4lfte des 170 Kilometer langen Rennens brachte er zusammen mit drei weiteren Ausrei\u00dfern die Favoriten des Team Bora Hansgrohe m\u00e4chtig ins Schwitzen.<!--more--><br \/>\nW\u00e4hrend das deutsche World-Tour Team vor allem auf seine Kapit\u00e4ne Lennart Kemmna und Pascal Ackermann setzte und einen Massensprint anpeilte, versuchten sich alle anderen Teams in Sachen Attacke. Die schwierigen Windverh\u00e4ltnisse, einsetzender Regen und die Dominanz Boras verhinderten weitere nennenswerte Angriffe. Bester Sauerl\u00e4nder wurde am Ende Per Christian M\u00fcnstermann auf dem 27. Platz. \u201eW\u00e4hrend wir im Rennen auf der H\u00f6he waren, ging es im Finale etwas daneben. Johannes Hodapp lag bis kurz vorm Ziel auf &#8222;Top Ten&#8220; Kurs und wurde durch einen Defekt zur\u00fcckgeworfen, Per Christian M\u00fcnstermann kam nicht richtig nach vorn\u201c, zeigte sich Coach Wolfgang Oschwald etwas ern\u00fcchtert vom reinen Ergebnis.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Spitzenplatzierungen bei der Baltic Chain Tour durch Estland und Lettland<\/b><\/p>\n<p>Mit drei Top Ten Platzierungen und einem Husarenritt auf der Abschlussetappe kehrte das Team SKS Sauerland NRW letzte Woche von der Baltic Chain Tour zur\u00fcck.<br \/>\nDie Rundfahrt durch Estland und Lettland ging \u00fcber vier Etappen. Diese waren zwischen 106 und 195 Kilometer lang. Trotz der versch\u00e4rften Corona Regeln gelang es dem Veranstalter ein bestens organisiertes Radrennen auszurichten. Bereits beim Auftakt im Herzen von Tallinn z\u00e4hlten die Sauerl\u00e4nder zu den<br \/>\nangriffslustigsten Fahrern im Feld, waren in jeder Spitzengruppe zu finden. Mit Lars Kulbe auf Platz vier schrammte man zwar knapp am Podium vorbei, war aber trotzdem zufrieden mit dem Resultat des j\u00fcngsten Sportlers der Mannschaft. Das es auf den folgenden Tagen einmal zum 12. und nochmals zu einem 4. Platz reichte, wurmte Kulbe dann aber doch. \u201eDreimal mit der Holzmedaille ins Hotel zu fahren war ungl\u00fccklich. Trotzdem sind wir stolz dem Rennen einen Stempel aufgedr\u00fcckt zu haben\u201c, so der sportliche Leiter Markus Mooser, welcher zusammen mit Lennart Bechheim das Team vor Ort betreute. Neben Lars Kulbe sorgte Jon Knolle noch f\u00fcr Aufsehen. Auf dem 175 Kilometer langen Abschnitt rund um die Stadt Valga initiierte der starke Zeitfahrer eine dreik\u00f6pfige Spitzengruppe, welche sich fast die H\u00e4lfte vom Rennen an der Spitze hielt. Als der Vorsprung rund 20 Kilometer vor dem Ziel unter eine Minute aus das Hauptfeld gefallen ist, machten sich alle zu einem Massensprint bereit. Keiner der Sprinterteams hat mit der Gegenwehr von Knolle gerechnet. Erst 1000 Meter vor dem Ziel wurde das Talent von der jagenden Meute eingeholt und rollte entt\u00e4uscht ins Ziel. Zwischenzeitlich war Jon Knolle virtueller F\u00fchrender der Rundfahrt und gewann alle Sprintwertungen w\u00e4hrend seiner Flucht. Teamintern beeindruckte die Fahrweise von Lars Kulbe, Jon Knolle, Louis und Joann Leinau, Johannes Adamietz, Michel Gie\u00dfelmann und Jon Knolle. Jeder stellte sich in den Dienst des Teams und besonders die Leinau Zwillinge aus H\u00fcsten leisteten an der Spitze des Feldes unerm\u00fcdliche F\u00fchrungsarbeit f\u00fcr die Kollegen. Einziger Wermutstropfen war das Ausscheiden von Johannes Adamietz am letzten Tag. Knapp 15 Kilometer vor Ende der gesamten Rundfahrt ging der Nationalfahrer hart zu Boden und musste vor Ort und Stelle behandelt werden.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Harter Kampf bei der Tour Bitwa Warszawaska rund um Warschau<\/b><\/p>\n<p>W\u00e4hrend der eine Teil des Teams bei der Baltic Chain Tour fuhr, startete die andere H\u00e4lfte der Mannschaft bei der zeitgleich laufenden Tour Bitwa Warszawaska in Polen. Hier hatten die Sauerl\u00e4nder weniger Gl\u00fcck und besonders mit den schlechten Stra\u00dfenverh\u00e4ltnissen zu k\u00e4mpfen. Auf jeder Etappe waren mehrere Kopfsteinpflasterabschnitte und Sandwege zu befahren. Obwohl man im Peloton einiges gewohnt ist, sorgte die Streckenwahl f\u00fcr Proteste bei den Teams. Bereits am ersten Tag fielen zahlreiche Rennfahrer aus dem Ergebnis, mussten nach St\u00fcrzen ins Krankenhaus. Weiter gab es mehrere platte Reifen an Begleitfahrzeugen und ungew\u00f6hnlich viele Materialdefekte an den Rennr\u00e4dern.<br \/>\nBestes Ergebnis aus Sauerl\u00e4nder Sicht war der 4. Platz von Abram Stockman auf der 2. Etappe.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-16318\" src=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2020\/08\/FCS_2659-min-1-scaled.jpg\" alt=\"\" width=\"333\" height=\"500\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2020\/08\/FCS_2659-min-1-scaled.jpg 1707w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2020\/08\/FCS_2659-min-1-200x300.jpg 200w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2020\/08\/FCS_2659-min-1-683x1024.jpg 683w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2020\/08\/FCS_2659-min-1-768x1152.jpg 768w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2020\/08\/FCS_2659-min-1-1024x1536.jpg 1024w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2020\/08\/FCS_2659-min-1-1365x2048.jpg 1365w\" sizes=\"auto, (max-width: 333px) 100vw, 333px\" \/><\/p>\n<p align=\"center\"><i>Joann Leinau<br \/>\n(Quelle: Team SKS Sauerland NRW)<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>kind regards \/ C \u043d\u0430\u0438\u043b\u0443\u0447\u0448\u0438\u043c\u0438 \u043f\u043e\u0436\u0435\u043b\u0430\u043d\u0438\u044f\u043c\u0438!\/ mit sportlichen Gr\u00fc\u00dfen \/ met vriendelijke groet<\/p>\n<p>&nbsp;<\/p>\n<p><b>J\u00f6rg Scherf<\/b><br \/>\n<i>gesch\u00e4ftsf\u00fchrender Gesellschafter\/ CEO<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p><i>Eslohe, den 26.8.2020<\/i><\/p>\n<p><b>Deutsche Profimeisterschaft am Sachsenring<\/b><\/p>\n<p>Beim Aussenseitersieg des Cross-Spezialisten Marcel Meisen \u00fcberzeugte aus Sauerl\u00e4nder Sicht der H\u00fcstener Joann Leinau. Mit seinem Angriff \u00fcber knapp die H\u00e4lfte des 170 Kilometer langen Rennens brachte er zusammen mit drei weiteren Ausrei\u00dfern die Favoriten des Team Bora Hansgrohe m\u00e4chtig ins Schwitzen.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/16317\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,32,33],"tags":[1256,1258,1269,1274,218,256,337,558,1233,1249,1250],"class_list":["post-16317","post","type-post","status-publish","format-standard","hentry","category-strassenrennsport","category-vereine","category-rennsport","tag-lars-kulbe","tag-johannes-adamietz","tag-abram-stockman","tag-1274","tag-strasse","tag-dm","tag-jon-knolle","tag-louis-leinau","tag-per-christian-muenstermann","tag-joann-leinau","tag-michel-giesselmann","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/16317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=16317"}],"version-history":[{"count":2,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/16317\/revisions"}],"predecessor-version":[{"id":16320,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/16317\/revisions\/16320"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=16317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=16317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=16317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}