{"id":15849,"date":"2019-09-14T13:51:35","date_gmt":"2019-09-14T11:51:35","guid":{"rendered":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/?p=15849"},"modified":"2019-09-14T13:51:35","modified_gmt":"2019-09-14T11:51:35","slug":"hessmann-und-koch-starten-bei-der-strassen-wm-in-yorkshire","status":"publish","type":"post","link":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/15849\/","title":{"rendered":"He\u00dfmann und Koch starten bei der Stra\u00dfen WM in Yorkshire"},"content":{"rendered":"<p>Mit <strong>Michel He\u00dfmann<\/strong> und <strong>Franzi Koch<\/strong> hat der Bund Deutscher Radfahrer zwei RSVer f\u00fcr die Stra\u00dfen-WM benannt. Die Titelk\u00e4mpfe finden in der Zeit vom 22.09. \u2013 29.09.2019 in Yorkshire statt.<\/p>\n<p><!--more--><\/p>\n<p>W\u00e4hrend die Nominierung bei <strong>Michel He\u00dfmann<\/strong> keine gro\u00dfe \u00dcberraschung f\u00fcr die Verantwortlichen im RSV Unna ist, sieht es bei <strong>Franzi Koch<\/strong> ein wenig anders aus. Sie f\u00e4hrt in diesem Jahr ihr erstes Elite Jahr. Bei der Nominierung hat die vierte der Deutschen Meisterschaften unter anderem <strong>Charlotte Becker<\/strong> ausgestochen. Dabei hat ihr sicherlich der erste Sieg im Rahmen der Boels Ladies Tour geholfen im BDR nachdr\u00fccklich auf sich aufmerksam zu machen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>He\u00dfmann f\u00fchrt beim kleinen Giro d`Italia das deutsche Team an<\/strong><\/p>\n<p><strong>Michel He\u00dfmann<\/strong> ist nach seinem Sturz beim Zeitfahren im Rahmen der EM jetzt richtig hei\u00df. Er ist mit seinem Trainer vorab nach Yorkshire gereist, um sich die wellige und windanf\u00e4llige Strecke genau anzusehen. Alles ist ausgerichtet auf dieses eine gro\u00dfe Rennen. Der Giro della Lunigiana (ITA) nutzte er f\u00fcr seine Vorbereitung. Auf der ersten Etappe dominierte er lange Zeit das Rennen, f\u00fchrte zur Rennh\u00e4lfte mit drei Minuten im Alleingang. Am letzten Anstieg 15 km vor dem Ziel schmolz der Vorsprung sehr schnell, da die italienische Nationalmannschaft Druck machte. Am Ende kam er, beim Sieg des Dt. Meisters Marco Brenner, mit 45 Sekunden R\u00fcckstand ins Ziel.<\/p>\n<p><strong>Michel He\u00dfmann<\/strong> fuhr in den weiteren Tagen immer wieder Top Ten Ergebnisse ein. Auf der selektiven vierten Etappe um Casette, mit einer Bergankunft, kam er auf den vierten Tagesrang mit zw\u00f6lf Sekunden R\u00fcckstand. Im Gesamtklassement f\u00fcr <strong>He\u00dfmann<\/strong> auf einen starken f\u00fcnften Rang und wurde damit bester Deutscher.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Deutsche Meisterschaften in Genthin<\/strong><\/p>\n<p>Bereits wenige Tage sp\u00e4ter gewann He\u00dfmann mit dem NRW Vierer das Bundesliga-Zeitfahren \u00fcber 50 Kilometer in Genthin. Das Team ben\u00f6tigte 56 Minuten f\u00fcr die Strecke und siegte vor Bayern und Sachsen.<\/p>\n<p>An gleicher Stelle bestritten auch die Frauen ihr Bundesligarennen \u00fcber 40 Kilometer. Das d.velop ladies team Quartett mit Tatjana Paller fuhr auf einen guten vierten Rang. Paller bereitet sich aktuell auf die im Oktober stattfindende Milit\u00e4r-WM vor.<\/p>\n<p>Bei dem als DM gewerteten Mannschaftszeitfahren der Elite fuhr Jon Knolle mit seinem Team Sauerland NRW auf den sechsten und Like Derksen mit dem Team Sportforum (D\u00fcsseldorf) auf den elften Rang.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>NRW Meisterschaften im Bergzeitfahren<\/strong><\/p>\n<p>Im sauerl\u00e4ndischen Winterberg fanden in diesem Jahr die NRW Meisterschaften im Bergzeitfahren statt. Den Titel f\u00fcr den RSV Unna sicherte sich Markus Vo\u00df in der Senioren 3 Klasse. Nach 8 Kilometern am Berg kam er mit einem Schnitt knapp unter 30 Km\/h in Ziel.<\/p>\n<p>Keine Chance um den Sieg mitzufahren hatten die Sprinter des RSV Unna in der U13. Daf\u00fcr k\u00e4mpften Colin Plich und Jonathan M\u00fcller bis zum letzten Meter um die Bronzemedaille. Am Ende landete Colin nach vier Kilometern mit einem winzigen Vorsprung von 0,5 Sekunden vor Jonathan. Auf Platz neun fuhr Tom Wendel. Bei der U15 fuhr Lasse Schenkmann in seinem ersten Zeitfahren auf den elften Rang.<\/p>\n<p>Bei den J\u00fcngsten war es erneut Paul Wendel, der mit Platz zwei auf sich aufmerksam machte. Auf Patz drei fuhr seine Zwillingsschwester Josephine, die damit gleich die Wertung der weiblichen Klasse gewann.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><b>Justin Wolf mit internationalem Podest<\/b><\/p>\n<p>Er ist ein Spezialist auf dem Zeitfahrrad. Mit seinen starken Ergebnissen in den vergangenen Jahren machte er hier immer mehr auf sich aufmerksam. In China verpasste er vor wenigen Wochen noch sein erstes internationales Treppchen. Bei der 30. Auflage des franz\u00f6sischen Zeitfahr-Wettbewerbes Chrono Champenois, eingestuft als UCI-Rennen der Kategorie 1.2, setzte der Mannschafts-EM Zweite nun sein pers\u00f6nliches Highlight.<\/p>\n<p>Bei den M\u00e4nnern musste sich Justin Wolf (Bike Aid) nur dem U23-Weltmeister im Einzelzeitfahren, Mikkel Bjerg (Hagens Berman Axeon), geschlagen geben und wurde Zweiter. Der D\u00e4ne legte die 33,4 Kilometer in 40:32 Minuten zur\u00fcck und war damit 24 Sekunden schneller als Wolf.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15850\" src=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0017-min.jpg\" alt=\"\" width=\"243\" height=\"500\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0017-min.jpg 778w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0017-min-146x300.jpg 146w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0017-min-768x1579.jpg 768w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0017-min-498x1024.jpg 498w\" sizes=\"auto, (max-width: 243px) 100vw, 243px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-15851\" src=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0012-min.jpg\" alt=\"\" width=\"500\" height=\"375\" border=\"1\" srcset=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0012-min.jpg 1600w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0012-min-300x225.jpg 300w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0012-min-768x576.jpg 768w, https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-content\/uploads\/2019\/09\/IMG-20190907-WA0012-min-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2 align=\"center\"><strong><em>Text und Fotos: RSV Unna<\/em><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit Michel He\u00dfmann und Franzi Koch hat der Bund Deutscher Radfahrer zwei RSVer f\u00fcr die Stra\u00dfen-WM benannt. Die Titelk\u00e4mpfe finden in der Zeit vom 22.09. \u2013 29.09.2019 in Yorkshire statt.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/15849\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,33],"tags":[211,212,218,220,221,239,244,246,256,258,60,337,71,404,129,512,130,703,131,1247,210,1248],"class_list":["post-15849","post","type-post","status-publish","format-standard","hentry","category-strassenrennsport","category-rennsport","tag-tatjana-paller","tag-bundesliga","tag-strasse","tag-michel-hessmann","tag-wm","tag-colin-plich","tag-jonathan-mueller","tag-luke-derksen","tag-dm","tag-franziska-koch","tag-60","tag-jon-knolle","tag-rsv-unna","tag-markus-voss","tag-paul-wendel","tag-lasse-schenkmann","tag-josefine-wendel","tag-lvm-nrw","tag-tom-wendel","tag-nrw-vierer","tag-justin-wolf","tag-jon","wp-image-borders","item-wrap"],"_links":{"self":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/15849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/comments?post=15849"}],"version-history":[{"count":1,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/15849\/revisions"}],"predecessor-version":[{"id":15852,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/posts\/15849\/revisions\/15852"}],"wp:attachment":[{"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/media?parent=15849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/categories?post=15849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radsportbezirk-westfalen-mitte.de\/wordpress\/wp-json\/wp\/v2\/tags?post=15849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}